{"id":11363,"count":2,"description":"","link":"https:\/\/palam.ca\/en\/tag\/google-duo-en\/","name":"Google Duo","slug":"google-duo-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Google Duo Archives | Palam<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/palam.ca\/en\/tag\/google-duo-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Google Duo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/palam.ca\/en\/tag\/google-duo-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Palam\" \/>\n<meta property=\"og:image\" content=\"https:\/\/palam.ca\/wp-content\/uploads\/2017\/05\/Palam_retina.png\" \/>\n\t<meta property=\"og:image:width\" content=\"511\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Palamca\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Google Duo Archives | Palam","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/palam.ca\/en\/tag\/google-duo-en\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Google Duo","og_url":"https:\/\/palam.ca\/en\/tag\/google-duo-en\/","og_site_name":"Palam","og_image":[{"width":511,"height":150,"url":"https:\/\/palam.ca\/wp-content\/uploads\/2017\/05\/Palam_retina.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Palamca","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/palam.ca\/en\/tag\/google-duo-en\/","url":"https:\/\/palam.ca\/en\/tag\/google-duo-en\/","name":"Google Duo Archives | Palam","isPartOf":{"@id":"https:\/\/palam.ca\/#website"},"breadcrumb":{"@id":"https:\/\/palam.ca\/en\/tag\/google-duo-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/palam.ca\/en\/tag\/google-duo-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/palam.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Google Duo"}]},{"@type":"WebSite","@id":"https:\/\/palam.ca\/#website","url":"https:\/\/palam.ca\/","name":"Palam","description":"Votre site d&#039;actualit\u00e9s","publisher":{"@id":"https:\/\/palam.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/palam.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/palam.ca\/#organization","name":"Palam.ca","url":"https:\/\/palam.ca\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/palam.ca\/#\/schema\/logo\/image\/","url":"https:\/\/palam.ca\/wp-content\/uploads\/2016\/07\/Palam-11.jpg","contentUrl":"https:\/\/palam.ca\/wp-content\/uploads\/2016\/07\/Palam-11.jpg","width":"800","height":"400","caption":"Palam.ca"},"image":{"@id":"https:\/\/palam.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PalamBuzzFun\/","https:\/\/x.com\/Palamca","https:\/\/palam.ca\/wp-content\/uploads\/2018\/02\/instagram.png","https:\/\/www.linkedin.com\/company\/palam.ca","https:\/\/www.youtube.com\/channel\/UCOxcqJVWjWz30B4F6ALHfqA\/"]}]}},"_links":{"self":[{"href":"https:\/\/palam.ca\/en\/wp-json\/wp\/v2\/tags\/11363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palam.ca\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/palam.ca\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/palam.ca\/en\/wp-json\/wp\/v2\/posts?tags=11363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}